{"id":167,"count":2,"description":"","link":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/","name":"\u6307\u5bfc","slug":"guide","taxonomy":"category","parent":0,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/category\\\/guide\\\/#listItem\",\"name\":\"Guide\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/category\\\/guide\\\/#listItem\",\"position\":2,\"name\":\"Guide\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/#collectionpage\",\"url\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/\",\"name\":\"Guide - Alta Vista de Boracay\",\"inLanguage\":\"zh-CN\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/#organization\",\"name\":\"Alta Vista de Boracay\",\"url\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/\",\"telephone\":\"+63362889888\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/altavistadeboracay.com.ph\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/alta-vista-logo-black.png\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/#organizationLogo\"},\"image\":{\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/167\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/altavistadeboracay\",\"https:\\\/\\\/www.instagram.com\\\/altavistadeboracay?igsh=bXVqc29qNTV2Nzdw\",\"https:\\\/\\\/www.tiktok.com\\\/@altavistadeboracay_?_t=ZS-90CYOaDdtbe&_r=1\"]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/#website\",\"url\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/\",\"name\":\"Alta Vista de Boracay\",\"inLanguage\":\"zh-CN\",\"publisher\":{\"@id\":\"http:\\\/\\\/altavistadeboracay.com.ph\\\/zh-cn\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Guide - Alta Vista de Boracay","description":"","canonical_url":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn#listItem","position":1,"name":"Home","item":"http:\/\/altavistadeboracay.com.ph\/zh-cn","nextItem":{"@type":"ListItem","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/#listItem","name":"Guide"}},{"@type":"ListItem","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/#listItem","position":2,"name":"Guide","previousItem":{"@type":"ListItem","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/#collectionpage","url":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/","name":"Guide - Alta Vista de Boracay","inLanguage":"zh-CN","isPartOf":{"@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/#website"},"breadcrumb":{"@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/#breadcrumblist"}},{"@type":"Organization","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/#organization","name":"Alta Vista de Boracay","url":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/","telephone":"+63362889888","logo":{"@type":"ImageObject","url":"https:\/\/altavistadeboracay.com.ph\/wp-content\/uploads\/2025\/07\/alta-vista-logo-black.png","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/#organizationLogo"},"image":{"@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/altavistadeboracay","https:\/\/www.instagram.com\/altavistadeboracay?igsh=bXVqc29qNTV2Nzdw","https:\/\/www.tiktok.com\/@altavistadeboracay_?_t=ZS-90CYOaDdtbe&_r=1"]},{"@type":"WebSite","@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/#website","url":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/","name":"Alta Vista de Boracay","inLanguage":"zh-CN","publisher":{"@id":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/altavistadeboracay.com.ph\/zh-cn\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGuide\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/altavistadeboracay.com.ph\/zh-cn"},{"label":"Guide","link":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/category\/guide\/"}],"_links":{"self":[{"href":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/altavistadeboracay.com.ph\/zh-cn\/wp-json\/wp\/v2\/posts?categories=167"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}